{"id":16243,"date":"2024-06-03T09:15:00","date_gmt":"2024-06-03T07:15:00","guid":{"rendered":"http:\/\/www.arepoquality.eu\/?p=16243"},"modified":"2024-06-03T16:08:01","modified_gmt":"2024-06-03T14:08:01","slug":"geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off","status":"publish","type":"post","link":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/","title":{"rendered":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART!"},"content":{"rendered":"\n<p>Nos complace anunciar que, durante <strong><span style=\"color:#F27F00\" class=\"color\">los pr\u00f3ximos<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\"> <\/span><strong><span style=\"color:#F27F00\" class=\"color\">4 a\u00f1os<\/span><\/strong>, AREPO participar\u00e1 activamente en un <strong><span style=\"color:#F27F00\" class=\"color\">proyecto pionero<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\"> <\/span><strong><span style=\"color:#F27F00\" class=\"color\">destinado a investigar los impactos de las Indicaciones Geogr\u00e1ficas (IG) en t\u00e9rminos de sostenibilidad y<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\"> <\/span><strong><span style=\"color:#F27F00\" class=\"color\">su contribuci\u00f3n al desarrollo sostenible<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\">. <\/span><\/p>\n\n\n\n<p>El proyecto, titulado <strong><span style=\"color:#F27F00\" class=\"color\">\u00abGI-SMART\u00bb<\/span><\/strong>, ha sido seleccionado en el marco de la convocatoria de Horizon Europe \u00abHORIZON-CL6-2023-COMMUNITIES: Investigaci\u00f3n de la contribuci\u00f3n de las indicaciones geogr\u00e1ficas (IG) al desarrollo sostenible y optimizaci\u00f3n del apoyo a los reg\u00edmenes de reciente creaci\u00f3n.\u00bb<\/p>\n\n\n\n<p><strong><span style=\"color:#F27F00\" class=\"color\">El proyecto comenz\u00f3 oficialmente el 1 de junio y contar\u00e1 con un presupuesto total de 2.554.531,67 euros.<\/span><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color:#F27F00\" class=\"color\">Objetivos del proyecto y principales resultados esperados<\/span><\/strong><\/h2>\n\n\n\n<p> El principal objetivo del proyecto es <strong><span style=\"color:#F27F00\" class=\"color\">mejorar el dise\u00f1o y la aplicaci\u00f3n del sistema de indicaciones geogr\u00e1ficas para apoyar la agricultura sostenible, los alimentos sanos y sostenibles y los sistemas alimentarios sostenibles, en consonancia con los objetivos de la estrategia \u00abde la granja a la mesa\u00bb<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\">.<\/span> Entre sus objetivos clave figuran:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desarrollar un s\u00f3lido estado del arte en la investigaci\u00f3n sobre la sostenibilidad de las IG y sus nuevos retos;<\/li>\n\n\n\n<li>Crear un m\u00e9todo de evaluaci\u00f3n cuantitativa reproducible y exhaustivo de las IG sostenibles (en sus dimensiones medioambiental, social, econ\u00f3mica y de gobernanza);<\/li>\n\n\n\n<li>Identificar y cartografiar las buenas pr\u00e1cticas para mejorar la sostenibilidad de las IG;<\/li>\n\n\n\n<li>Explorar y comparar los enfoques y pol\u00edticas de los Estados miembros;<\/li>\n\n\n\n<li>Analizar y mejorar la comprensi\u00f3n de la sostenibilidad de las IG por parte de los consumidores locales y mundiales;<\/li>\n\n\n\n<li>Formular recomendaciones pol\u00edticas, herramientas de decisi\u00f3n y mejores pr\u00e1cticas para que los responsables pol\u00edticos y los productores mejoren la sostenibilidad de las IG;<\/li>\n\n\n\n<li>Crear una plataforma comunitaria GI Smart para la comunicaci\u00f3n, difusi\u00f3n y explotaci\u00f3n de los resultados del proyecto y la participaci\u00f3n de las partes interesadas.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png\" alt=\"\" class=\"wp-image-16208\" srcset=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png 300w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-150x150.png 150w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-320x320.png 320w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image.png 497w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>El trabajo realizado a lo largo de este proyecto de cuatro a\u00f1os dar\u00e1 lugar a un conjunto de recomendaciones pol\u00edticas y tres gu\u00edas estrat\u00e9gicas:<\/p>\n\n\n\n<div class=\"wp-block-columns has-3-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong><span style=\"color:#F27F00\" class=\"color\">1.&nbsp;Gu\u00eda para agrupaciones de productores de IG<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\">, <\/span>que recoge pr\u00e1cticas y v\u00edas eficaces de sostenibilidad, con el objetivo de mejorar la contribuci\u00f3n de las IG a la sostenibilidad econ\u00f3mica, medioambiental y social; <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong><span style=\"color:#F27F00\" class=\"color\">2.<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\"> <\/span><strong><span style=\"color:#F27F00\" class=\"color\">Gu\u00eda para los responsables pol\u00edticos destinada a<\/span> <\/strong>crear un entorno pol\u00edtico que apoye a las partes interesadas en las IG en la mejora de la sostenibilidad (desde el nivel local, regional y nacional hasta el de la UE); <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong><span style=\"color: #f27f00;\" class=\"color\">3.&nbsp;<\/span><span style=\"color:#F27F00\" class=\"color\">Gu\u00eda para mejorar la comercializaci\u00f3n de las IG<\/span> <\/strong>destinada a las agrupaciones de productores y otras partes interesadas.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color:#F27F00\" class=\"color\">Consorcio GI Smart y socios<\/span><\/strong><\/h2>\n\n\n\n<p>AREPO ser\u00e1 un miembro activo de un <strong><span style=\"color:#F27F00\" class=\"color\">consorcio formado por 17 socios p\u00fablicos y privados de 8 EM europeos<\/span> <\/strong>(Francia, Alemania, Grecia, Hungr\u00eda, Italia, Portugal, Espa\u00f1a), <strong><span style=\"color:#F27F00\" class=\"color\">del Reino Unido y Suiza<\/span><\/strong>. Estar\u00e1 <strong><span style=\"color:#F27F00\" class=\"color\">coordinado por el INRAE<\/span> <\/strong>&#8211; Instituto Nacional de Investigaci\u00f3n para la Agricultura, la Alimentaci\u00f3n y el Medio Ambiente (Francia) e incluir\u00e1 tambi\u00e9n a varios miembros del Consejo Cient\u00edfico de AREPO y a anteriores socios del <a href=\"https:\/\/www.strength2food.eu\/\">proyecto Strength2food de H2020<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color:#F27F00\" class=\"color\">El papel de AREPO<\/span><\/strong><\/h2>\n\n\n\n<p>AREPO desempe\u00f1ar\u00e1 un papel en\nmuchas de las actividades de investigaci\u00f3n previstas por el proyecto y ayudar\u00e1\na otros socios en sus tareas. &nbsp;<\/p>\n\n\n\n<p>En particular, <strong><span style=\"color:#F27F00\" class=\"color\">AREPO ser\u00e1 el l\u00edder del paquete de trabajo para la comunicaci\u00f3n, difusi\u00f3n, explotaci\u00f3n y participaci\u00f3n de las partes interesadas, en colaboraci\u00f3n con Euromontana,<\/span> <\/strong>para garantizar la asimilaci\u00f3n de la investigaci\u00f3n cient\u00edfica por parte de los productores de IG, as\u00ed como de las administraciones p\u00fablicas (regionales, nacionales y de la UE).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color:#F27F00\" class=\"color\">Plataforma comunitaria GI Smart<\/span><\/strong><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/community-platform-300x300.png\" alt=\"\" class=\"wp-image-16219\" style=\"width:150px;height:150px\" srcset=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/community-platform-300x300.png 300w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/community-platform-150x150.png 150w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/community-platform-320x320.png 320w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/community-platform.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>La participaci\u00f3n de las partes interesadas se llevar\u00e1 a cabo mediante<span style=\"color:#F27F00\" class=\"color\"> <\/span><strong><span style=\"color:#F27F00\" class=\"color\">la creaci\u00f3n de una plataforma multiactores a nivel nacional y de la UE que incluya a productores, consumidores, organismos de control y autoridades regionales y nacionales<\/span><\/strong><span style=\"color:#F27F00\" class=\"color\">. <\/span>Ayudar\u00e1 a crear un intercambio de conocimientos entre las distintas partes interesadas de toda la UE y a recabar opiniones y aportaciones sobre las actividades del proyecto (por ejemplo, validaci\u00f3n del marco conceptual y anal\u00edtico; opiniones sobre la definici\u00f3n de la metodolog\u00eda; debate sobre los resultados de la investigaci\u00f3n; validaci\u00f3n de las recomendaciones pol\u00edticas; difusi\u00f3n de los resultados del proyecto y de las directrices estrat\u00e9gicas).<\/p>\n\n\n\n<p>Los socios del proyecto se reunir\u00e1n en Par\u00eds despu\u00e9s del verano para la reuni\u00f3n de lanzamiento. Permanezcan atentos! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace anunciar que, durante los pr\u00f3ximos 4 a\u00f1os, AREPO participar\u00e1 activamente en un proyecto pionero destinado a investigar los impactos de las Indicaciones Geogr\u00e1ficas (IG) en t\u00e9rminos de sostenibilidad y su contribuci\u00f3n al desarrollo sostenible. El proyecto, titulado \u00abGI-SMART\u00bb, ha sido seleccionado en el marco de la convocatoria de Horizon Europe \u00abHORIZON-CL6-2023-COMMUNITIES: Investigaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[490,483],"tags":[],"class_list":["post-16243","post","type-post","status-publish","format-standard","hentry","category-gi-smart-5","category-horizoneurope-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO\" \/>\n<meta property=\"og:description\" content=\"Nos complace anunciar que, durante los pr\u00f3ximos 4 a\u00f1os, AREPO participar\u00e1 activamente en un proyecto pionero destinado a investigar los impactos de las Indicaciones Geogr\u00e1ficas (IG) en t\u00e9rminos de sostenibilidad y su contribuci\u00f3n al desarrollo sostenible. El proyecto, titulado \u00abGI-SMART\u00bb, ha sido seleccionado en el marco de la convocatoria de Horizon Europe \u00abHORIZON-CL6-2023-COMMUNITIES: Investigaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/\" \/>\n<meta property=\"og:site_name\" content=\"AREPO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arepoquality\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T07:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T14:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png\" \/>\n<meta name=\"author\" content=\"Francesca Alampi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:site\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Alampi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/\"},\"author\":{\"name\":\"Francesca Alampi\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\"},\"headline\":\"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART!\",\"datePublished\":\"2024-06-03T07:15:00+00:00\",\"dateModified\":\"2024-06-03T14:08:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/\"},\"wordCount\":769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image-300x300.png\",\"articleSection\":[\"GI-SMART\",\"HorizonEurope\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/\",\"name\":\"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image-300x300.png\",\"datePublished\":\"2024-06-03T07:15:00+00:00\",\"dateModified\":\"2024-06-03T14:08:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image-300x300.png\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/2024\\\/06\\\/03\\\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arepoquality.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"name\":\"AREPO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arepoquality.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\",\"name\":\"AREPO\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"width\":1113,\"height\":705,\"caption\":\"AREPO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arepoquality\\\/\",\"https:\\\/\\\/x.com\\\/arepoquality_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arepoquality\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\",\"name\":\"Francesca Alampi\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/es\\\/author\\\/francesca-alampi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/","og_locale":"es_ES","og_type":"article","og_title":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO","og_description":"Nos complace anunciar que, durante los pr\u00f3ximos 4 a\u00f1os, AREPO participar\u00e1 activamente en un proyecto pionero destinado a investigar los impactos de las Indicaciones Geogr\u00e1ficas (IG) en t\u00e9rminos de sostenibilidad y su contribuci\u00f3n al desarrollo sostenible. El proyecto, titulado \u00abGI-SMART\u00bb, ha sido seleccionado en el marco de la convocatoria de Horizon Europe \u00abHORIZON-CL6-2023-COMMUNITIES: Investigaci\u00f3n de [&hellip;]","og_url":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/","og_site_name":"AREPO","article_publisher":"https:\/\/www.facebook.com\/arepoquality\/","article_published_time":"2024-06-03T07:15:00+00:00","article_modified_time":"2024-06-03T14:08:01+00:00","og_image":[{"url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png","type":"","width":"","height":""}],"author":"Francesca Alampi","twitter_card":"summary_large_image","twitter_creator":"@arepoquality_eu","twitter_site":"@arepoquality_eu","twitter_misc":{"Escrito por":"Francesca Alampi","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#article","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/"},"author":{"name":"Francesca Alampi","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97"},"headline":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART!","datePublished":"2024-06-03T07:15:00+00:00","dateModified":"2024-06-03T14:08:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/"},"wordCount":769,"commentCount":0,"publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"image":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png","articleSection":["GI-SMART","HorizonEurope"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/","url":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/","name":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART! - AREPO","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#primaryimage"},"image":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png","datePublished":"2024-06-03T07:15:00+00:00","dateModified":"2024-06-03T14:08:01+00:00","breadcrumb":{"@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#primaryimage","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/image-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arepoquality.eu\/es\/2024\/06\/03\/geographical-indications-contribution-to-smart-territorial-development-and-sustainability-gi-smart-ready-to-kick-off\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arepoquality.eu\/"},{"@type":"ListItem","position":2,"name":"La contribuci\u00f3n de las Indicaciones Geogr\u00e1ficas al desarrollo territorial inteligente y a la sostenibilidad: \u00a1comienza GI-SMART!"}]},{"@type":"WebSite","@id":"https:\/\/www.arepoquality.eu\/#website","url":"https:\/\/www.arepoquality.eu\/","name":"AREPO","description":"","publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arepoquality.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arepoquality.eu\/#organization","name":"AREPO","url":"https:\/\/www.arepoquality.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","width":1113,"height":705,"caption":"AREPO"},"image":{"@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arepoquality\/","https:\/\/x.com\/arepoquality_eu","https:\/\/www.linkedin.com\/company\/arepoquality\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97","name":"Francesca Alampi","url":"https:\/\/www.arepoquality.eu\/es\/author\/francesca-alampi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/posts\/16243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/comments?post=16243"}],"version-history":[{"count":3,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/posts\/16243\/revisions"}],"predecessor-version":[{"id":16276,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/posts\/16243\/revisions\/16276"}],"wp:attachment":[{"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/media?parent=16243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/categories?post=16243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/es\/wp-json\/wp\/v2\/tags?post=16243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}