{"id":2598,"date":"2021-07-08T17:34:49","date_gmt":"2021-07-08T15:34:49","guid":{"rendered":"http:\/\/252373706c.url-de-test.ws\/arepo\/?post_type=politics&#038;p=2598"},"modified":"2024-06-11T16:29:42","modified_gmt":"2024-06-11T14:29:42","slug":"farm-to-fork-strategy","status":"publish","type":"politics","link":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/","title":{"rendered":"De la Ferme \u00e0 la Table"},"content":{"rendered":"\n<p class=\"has-text-align-center has-blue-navy-color has-text-color\"><i><span> <\/span>La strat\u00e9gie \u00ab\u00a0De la Ferme \u00e0 la Table\u00a0\u00bb est la feuille de route europ\u00e9enne pour relever le d\u00e9fi de la conception d&rsquo;un syst\u00e8me alimentaire \u00e9quitable, sain et respectueux de l&rsquo;environnement. Puisque cette strat\u00e9gie doit d\u00e9finir les mesures r\u00e9glementaires et non r\u00e9glementaires n\u00e9cessaires pour atteindre cet objectif, plusieurs actions propos\u00e9es par la Commission dans ce cadre int\u00e9ressent directement les syst\u00e8mes de qualit\u00e9 de l&rsquo;UE. <\/i><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#004386\" class=\"color\">Introduction<\/span><\/h2>\n\n\n\n<p>Le <a href=\"https:\/\/ec.europa.eu\/info\/strategy\/priorities-2019-2024\/european-green-deal_fr\">Pacte vert pour l\u2019Europe<\/a> confie \u00e0 la strat\u00e9gie <a href=\"https:\/\/ec.europa.eu\/food\/horizontal-topics\/farm-fork-strategy_en\">\u00ab\u00a0De la ferme \u00e0 la table\u00a0\u00bb<\/a> la t\u00e2che de concevoir un <strong>syst\u00e8me alimentaire \u00e9quitable, sain et respectueux de l&rsquo;environnement<\/strong>, avec l&rsquo;ambition <strong>de <em>\u00ab\u00a0faire de l&rsquo;alimentation europ\u00e9enne [\u2026] la norme mondiale en mati\u00e8re de durabilit\u00e9\u00a0\u00bb<\/em><\/strong>.<\/p>\n\n\n\n<p>Le 20 mai 2020, la Commission a publi\u00e9 la Communication et le Plan d&rsquo;Action de la strat\u00e9gie \u00ab\u00a0De la ferme \u00e0 la table\u00a0\u00bb, fixant des objectifs et des cibles \u00e0 atteindre d&rsquo;ici 2030 :<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\"><span style=\"color:#004386\" class=\"color\">Objectifs sp\u00e9cifiques<\/span><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\"><span style=\"color:#004386\" class=\"color\">Objectifs pour 2030<\/span>\ufeff<\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column\">\n<ul>\n<li>Garantir une <strong>production alimentaire durable <\/strong><\/li>\n<li>Garantir la <strong>s\u00e9curit\u00e9 alimentaire <\/strong><\/li>\n<li>Stimuler les <strong>pratiques durables en mati\u00e8re de transformation des aliments, de vente en gros, et au d\u00e9tail, d&rsquo;h\u00f4tellerie et de restauration<\/strong><\/li>\n<li>Promouvoir une <strong>consommation alimentaire durable<\/strong> et faciliter le passage \u00e0 des <strong>r\u00e9gimes alimentaires sains et durables<\/strong><\/li>\n<li>R\u00e9duire les <strong>pertes et le gaspillage de nourriture<\/strong><\/li>\n<li>Lutter contre la <strong>fraude alimentaire<\/strong> tout au long de la cha\u00eene d&rsquo;approvisionnement alimentaire<\/li>\n<\/ul>\n<\/div>\n<div class=\"wp-block-column\">\n<ul>\n<li style=\"text-align: left;\"><strong>La r\u00e9duction de 50% de l&rsquo;utilisation et des risques li\u00e9s aux pesticides chimiques<\/strong><\/li>\n<li style=\"text-align: left;\">La r\u00e9duction de 50% de l&rsquo;utilisation de <strong>pesticides plus dangereux<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>La r\u00e9duction des pertes de nutriments d&rsquo;au moins 50%<\/strong><\/li>\n<li>La r\u00e9duction de l&rsquo;utilisation d&rsquo;engrais d&rsquo;au moins 20%<\/li>\n<li><strong>La r\u00e9duction de 50% des ventes d&rsquo;antimicrobiens<\/strong> pour les animaux d&rsquo;\u00e9levage et dans l&rsquo;aquaculture<\/li>\n<li><strong>Atteindre 25 % des terres agricoles en agriculture biologique d&rsquo;ici 2030<\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#004386\" class=\"color\">Nouvelles politiques et application de la l\u00e9gislation existante <\/span>\ufeff<\/h2>\n\n\n\n<p>Afin d&rsquo;atteindre ces objectifs et de r\u00e9aliser ces buts, la strat\u00e9gie Farm to Fork implique une <strong>nouvelle s\u00e9rie d&rsquo;initiatives politiques<\/strong>, ainsi que <strong>l&rsquo;application de la l\u00e9gislation existante<\/strong>, notamment en ce qui concerne le bien-\u00eatre des animaux, l&rsquo;utilisation des pesticides et la l\u00e9gislation sur la protection de l&rsquo;environnement.<\/p>\n\n\n\n<p>En particulier, la Commission fera une <strong>proposition pour un cadre l\u00e9gislatif pour un syst\u00e8me alimentaire durable.<\/strong> <\/p>\n\n\n\n<p>Le cadre contiendra des <strong>d\u00e9finitions communes et des principes et exigences g\u00e9n\u00e9raux <\/strong>pour des syst\u00e8mes alimentaires et des aliments durables. En outre, il abordera<strong> les responsabilit\u00e9s de tous les acteurs<\/strong> du syst\u00e8me alimentaire.<\/p>\n\n\n\n<p>Parmi les actions que la Commission europ\u00e9enne entend mettre en \u0153uvre dans le cadre de la strat\u00e9gie \u00ab\u00a0de la ferme \u00e0 la table\u00a0\u00bb, certaines sont ax\u00e9es sur la priorit\u00e9 g\u00e9n\u00e9rale de la Commission consistant \u00e0 <strong>renforcer le syst\u00e8me des indications g\u00e9ographiques de l&rsquo;UE<\/strong>.<strong> <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#004386\" class=\"color\">Plus d&rsquo;informations<\/span>\ufeff<\/h2>\n\n\n\n<p>La strat\u00e9gie devant d\u00e9finir les mesures r\u00e9glementaires et non r\u00e9glementaires n\u00e9cessaires \u00e0 la conception d&rsquo;un syst\u00e8me alimentaire \u00e9quitable, sain et respectueux de l&rsquo;environnement, <strong>plusieurs actions propos\u00e9es par la Commission dans ce cadre int\u00e9ressent directement les syst\u00e8mes de qualit\u00e9 de l&rsquo;UE ainsi que d&rsquo;autres domaines de travail de l&rsquo;AREPO.<\/strong><\/p>\n\n\n<ul>\n<li><strong>Indications g\u00e9ographiques : <\/strong>la Commission renforcera le cadre l\u00e9gislatif relatif aux IG et, le cas \u00e9ch\u00e9ant, inclura des crit\u00e8res de durabilit\u00e9 sp\u00e9cifiques.\u00a0<a href=\"http:\/\/252373706c.url-de-test.ws\/arepo\/fr\/politics\/eu-quality-policy\/\"><em>Lire plus<\/em><\/a><\/li>\n<li><strong>Politique de promotion : <\/strong>la r\u00e9vision de la politique devrait \u00eatre ax\u00e9 sur le renforcement de sa contribution \u00e0 une production et une consommation durables, conform\u00e9ment \u00e0 l&rsquo;\u00e9volution des r\u00e9gimes alimentaires (<em>action 24<\/em>).<em>\u00a0<a href=\"http:\/\/252373706c.url-de-test.ws\/arepo\/fr\/politics\/la-politique-de-promotion-de-lue\/\">Lire plus<\/a><\/em><\/li>\n<li><strong>\u00c9tiquetage nutritionnel obligatoire harmonis\u00e9 sur le devant des emballages:<\/strong>la CE devrait publier une proposition d&rsquo;ici la fin de 2022\u00a0<em>(action 20)<\/em>.<\/li>\n<li><strong>Indication obligatoire de l&rsquo;origine: <\/strong>la CE travaillera sur une proposition visant \u00e0 \u00e9tendre le champ d&rsquo;application de l&rsquo;indication obligatoire de l&rsquo;origine\u00a0<em>(action 21)<\/em>.\u00a0<\/li>\n<li><strong>Autres initiatives en mati\u00e8re d&rsquo;\u00e9tiquetage alimentaire:<\/strong> la CE examinera les options d&rsquo;<strong>\u00e9tiquetage en ce qui concerne le bien-\u00eatre animal\u00a0<\/strong><em>(action 7)<\/em>\u00a0ainsi que les moyens d&rsquo;harmoniser les all\u00e9gations \u00e9cologiques volontaires et de <strong>cr\u00e9er un cadre d&rsquo;\u00e9tiquetage alimentaire durable<\/strong> qui couvre les aspects nutritionnels, climatiques, environnementaux et sociaux des produits alimentaires\u00a0<em>(action 23)<\/em>.<\/li>\n<li><strong>Agriculture biologique:<\/strong>\u00a0la Commission s&rsquo;est fix\u00e9 comme objectif d&rsquo;atteindre au moins 25 % des terres agricoles de l&rsquo;UE en agriculture biologique d&rsquo;ici 2030. En plus des mesures de la PAC, la Commission a pr\u00e9sent\u00e9 un <a href=\"https:\/\/ec.europa.eu\/info\/food-farming-fisheries\/farming\/organic-farming\/organic-action-plan_fr\"><strong>Plan d&rsquo;Action sur l&rsquo;agriculture biologique<\/strong><\/a> afin de stimuler \u00e0 la fois l&rsquo;offre et la demande de produits biologiques, par le biais de campagnes de promotion et de march\u00e9s publics \u00e9cologiques. <a href=\"http:\/\/252373706c.url-de-test.ws\/arepo\/fr\/politics\/agriculture-biologique\/\"><em>Lire plus<\/em><\/a><\/li>\n<li><strong>Profils nutritionnels: <\/strong>La Commission cherchera \u00e9galement des possibilit\u00e9s de faciliter le passage \u00e0 des r\u00e9gimes alimentaires plus sains et de stimuler la reformulation des produits (<em>action 15)<\/em>, notamment en \u00e9tablissant des profils nutritionnels pour limiter la promotion (par des all\u00e9gations nutritionnelles ou de sant\u00e9) d&rsquo;aliments riches en graisses, en sucres et en sel (<em>action 16<\/em>).<\/li>\n<li><strong>Approvisionnement alimentaire durable :<\/strong>\u00a0la Commission d\u00e9terminera les meilleures modalit\u00e9s pour fixer des crit\u00e8res minimaux obligatoires pour l&rsquo;achat de denr\u00e9es alimentaires durables (<em>action 22<\/em>).\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/li>\n<li><strong>Lutte contre la fraude alimentaire tout au long de la cha\u00eene d&rsquo;approvisionnement alimentaire:<\/strong>\u00a0la CE renforcera la coordination afin de faire respecter les r\u00e8gles du march\u00e9 unique et de lutter contre la fraude alimentaire, notamment en envisageant un recours accru aux capacit\u00e9s d&rsquo;enqu\u00eate de l&rsquo;OLAF (<em>action 19<\/em>).<\/li>\n<\/ul>","protected":false},"featured_media":10588,"template":"","class_list":["post-2598","politics","type-politics","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De la Ferme \u00e0 la Table - AREPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la Ferme \u00e0 la Table - AREPO\" \/>\n<meta property=\"og:description\" content=\"La strat\u00e9gie \u00ab\u00a0De la Ferme \u00e0 la Table\u00a0\u00bb est la feuille de route europ\u00e9enne pour relever le d\u00e9fi de la conception d&rsquo;un syst\u00e8me alimentaire \u00e9quitable, sain et respectueux de l&rsquo;environnement. Puisque cette strat\u00e9gie doit d\u00e9finir les mesures r\u00e9glementaires et non r\u00e9glementaires n\u00e9cessaires pour atteindre cet objectif, plusieurs actions propos\u00e9es par la Commission dans ce cadre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/\" \/>\n<meta property=\"og:site_name\" content=\"AREPO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arepoquality\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T14:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2021\/07\/Farm2Fork.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3012\" \/>\n\t<meta property=\"og:image:height\" content=\"2014\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/\",\"name\":\"De la Ferme \u00e0 la Table - AREPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Farm2Fork.png\",\"datePublished\":\"2021-07-08T15:34:49+00:00\",\"dateModified\":\"2024-06-11T14:29:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Farm2Fork.png\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Farm2Fork.png\",\"width\":3012,\"height\":2014},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/politics\\\/farm-to-fork-strategy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arepoquality.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De la Ferme \u00e0 la Table\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"name\":\"AREPO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arepoquality.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\",\"name\":\"AREPO\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"width\":1113,\"height\":705,\"caption\":\"AREPO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arepoquality\\\/\",\"https:\\\/\\\/x.com\\\/arepoquality_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arepoquality\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la Ferme \u00e0 la Table - AREPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/","og_locale":"fr_FR","og_type":"article","og_title":"De la Ferme \u00e0 la Table - AREPO","og_description":"La strat\u00e9gie \u00ab\u00a0De la Ferme \u00e0 la Table\u00a0\u00bb est la feuille de route europ\u00e9enne pour relever le d\u00e9fi de la conception d&rsquo;un syst\u00e8me alimentaire \u00e9quitable, sain et respectueux de l&rsquo;environnement. Puisque cette strat\u00e9gie doit d\u00e9finir les mesures r\u00e9glementaires et non r\u00e9glementaires n\u00e9cessaires pour atteindre cet objectif, plusieurs actions propos\u00e9es par la Commission dans ce cadre [&hellip;]","og_url":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/","og_site_name":"AREPO","article_publisher":"https:\/\/www.facebook.com\/arepoquality\/","article_modified_time":"2024-06-11T14:29:42+00:00","og_image":[{"width":3012,"height":2014,"url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2021\/07\/Farm2Fork.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@arepoquality_eu","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/","url":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/","name":"De la Ferme \u00e0 la Table - AREPO","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/#primaryimage"},"image":{"@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2021\/07\/Farm2Fork.png","datePublished":"2021-07-08T15:34:49+00:00","dateModified":"2024-06-11T14:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/#primaryimage","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2021\/07\/Farm2Fork.png","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2021\/07\/Farm2Fork.png","width":3012,"height":2014},{"@type":"BreadcrumbList","@id":"https:\/\/www.arepoquality.eu\/fr\/politics\/farm-to-fork-strategy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arepoquality.eu\/"},{"@type":"ListItem","position":2,"name":"De la Ferme \u00e0 la Table"}]},{"@type":"WebSite","@id":"https:\/\/www.arepoquality.eu\/#website","url":"https:\/\/www.arepoquality.eu\/","name":"AREPO","description":"","publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arepoquality.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.arepoquality.eu\/#organization","name":"AREPO","url":"https:\/\/www.arepoquality.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","width":1113,"height":705,"caption":"AREPO"},"image":{"@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arepoquality\/","https:\/\/x.com\/arepoquality_eu","https:\/\/www.linkedin.com\/company\/arepoquality\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/politics\/2598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/politics"}],"about":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/types\/politics"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media\/10588"}],"wp:attachment":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media?parent=2598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}