{"id":16423,"date":"2024-06-20T11:38:50","date_gmt":"2024-06-20T09:38:50","guid":{"rendered":"https:\/\/www.arepoquality.eu\/?p=16423"},"modified":"2024-07-05T08:54:12","modified_gmt":"2024-07-05T06:54:12","slug":"la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027","status":"publish","type":"post","link":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/","title":{"rendered":"La conf\u00e9rence finale de MOVING trace l&rsquo;avenir des zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Les 13 et 14 juin, la <a href=\"https:\/\/www.moving-h2020.eu\/event\/moving-final-conference\/\">conf\u00e9rence finale du projet MOVING <\/a>: \u00ab\u00a0Un avenir pour les zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\u00a0\u00bb s&rsquo;est tenue \u00e0 Bruxelles, marquant l&rsquo;aboutissement d&rsquo;un voyage de quatre ans pour le projet. Cet \u00e9v\u00e9nement de haut niveau de deux jours a rassembl\u00e9 plus de <strong>60 participants <\/strong>des institutions europ\u00e9ennes (<strong>Parlement europ\u00e9en, Commission europ\u00e9enne, Comit\u00e9 \u00e9conomique et social europ\u00e9en, Centre commun de recherche<\/strong>), des services de soutien de l&rsquo;UE (<strong>ESPON, Centre commun de recherche, Bureau de soutien du Pacte rural<\/strong>), des groupes de parties prenantes de l&rsquo;UE (<strong>Euromontana, AREPO)<\/strong>, de la communaut\u00e9 de la recherche et des acteurs locaux\/r\u00e9gionaux de la montagne pour souligner le r\u00f4le crucial des zones de montagne dans l&rsquo;avancement des objectifs politiques et des cibles de l&rsquo;Europe d&rsquo;ici \u00e0 2030.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organis\u00e9 par l&rsquo;Association europ\u00e9enne pour l&rsquo;innovation dans le d\u00e9veloppement local (AEIDL) et accueilli par l&rsquo;AREPO dans le cadre du projet H2020 <a href=\"https:\/\/www.moving-h2020.eu\/\">MOVING <\/a>(MOuntain Valorisation through INterconnectedness and Green Growth) financ\u00e9 par l&rsquo;UE, l&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 strat\u00e9giquement programm\u00e9 pour discuter du r\u00f4le central des montagnes et des cha\u00eenes de valeur de montagne dans la r\u00e9alisation des objectifs politiques de l&rsquo;Europe d&rsquo;ici 2030 et dans l&rsquo;\u00e9laboration de <strong>l&rsquo;agenda politique de l&rsquo;UE pour l&rsquo;apr\u00e8s-2027<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar Delgado<\/strong>, coordinatrice de MOVING et professeur \u00e0 l&rsquo;universit\u00e9 de Cordoue, a ouvert l&rsquo;\u00e9v\u00e9nement en affirmant : \u00ab\u00a0Ce n&rsquo;est pas la fin de MOVING, mais le d\u00e9but d&rsquo;un meilleur avenir pour les politiques de l&rsquo;UE en faveur des zones de montagne apr\u00e8s 2027.\u00a0\u00bb Ce sentiment a \u00e9t\u00e9 partag\u00e9 par les principaux intervenants qui ont soulign\u00e9 l&rsquo;importance d&rsquo;un soutien continu aux r\u00e9gions de montagne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mario Milouchev<\/strong>, directeur \u00e0 la direction D \u00ab\u00a0Plans strat\u00e9giques de la PAC II\u00a0\u00bb, \u00e0 la DG AGRI de la Commission europ\u00e9enne, a soulign\u00e9 le r\u00f4le essentiel des politiques de l&rsquo;UE dans le soutien aux r\u00e9gions rurales et de montagne. M. Milouchev a pr\u00e9sent\u00e9 les r\u00e9alisations et les prochaines \u00e9tapes du <a href=\"https:\/\/www.moving-h2020.eu\/news\/the-long-term-vision-for-the-eus-rural-areas-key-achievements-and-ways-forward\/\">bilan de la Vision \u00e0 long terme pour les zones rurales (LTVRA)<\/a>, notant que \u00ab\u00a0cette conf\u00e9rence sur les zones de montagne est une contribution utile au d\u00e9bat en cours sur les futures politiques de l&rsquo;UE apr\u00e8s 2027\u00a0\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-300x200.jpg\" alt=\"\" class=\"wp-image-16392\" srcset=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-300x200.jpg 300w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-1024x683.jpg 1024w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-768x512.jpg 768w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-1536x1024.jpg 1536w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-320x213.jpg 320w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-640x427.jpg 640w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-1280x853.jpg 1280w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480-1920x1280.jpg 1920w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6480.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La conf\u00e9rence a donn\u00e9 lieu \u00e0 des pr\u00e9sentations de la part des partenaires de MOVING afin de mettre en \u00e9vidence les d\u00e9fis et les opportunit\u00e9s au sein des cha\u00eenes de valeur de montagne. <a href=\"https:\/\/www.moving-h2020.eu\/wp-content\/uploads\/2023\/06\/MOVING_D4.6_Upgrading-Strategies.pdf\">De strat\u00e9gies multiples<\/a> pour am\u00e9liorer ces cha\u00eenes de valeur ont \u00e9t\u00e9 discut\u00e9es lors de la deuxi\u00e8me session de la conf\u00e9rence, mod\u00e9r\u00e9e par <strong>Giulia Scaglioni<\/strong>, Charg\u00e9e de mission \u00e0 l&rsquo;AREPO, parall\u00e8lement au <a href=\"https:\/\/www.moving-h2020.eu\/wp-content\/uploads\/2024\/06\/Repertoire-of-Strategic-Options.pdf\">R\u00e9pertoire des options strat\u00e9giques<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plusieurs tables rondes avec des experts, dont <strong>Wiktor Szydarowski<\/strong>, directeur d&rsquo;ESPON EGTC, <strong>Eleftherios Stavropoulos <\/strong>du Centre commun de recherche, <strong>Klavdija Ramsak-Noemi<\/strong> de la DG AGRI, <strong>Benoit Nadler<\/strong> de la DG REGIO, et <strong>Toma \u0160uti\u0107<\/strong>, membre du cabinet du vice-pr\u00e9sident charg\u00e9 de la d\u00e9mocratie et de la d\u00e9mographie \u00e0 la Commission europ\u00e9enne, se sont concentr\u00e9es sur l&rsquo;efficacit\u00e9 des solutions, des outils et des politiques n\u00e9cessaires pour soutenir les r\u00e9gions montagneuses. Ils ont soulign\u00e9 l&rsquo;importance cruciale de l&rsquo;int\u00e9gration des r\u00e9gions rurales et de montagne dans les politiques de l&rsquo;UE par le biais d&rsquo;outils innovants, de solutions \u00e9labor\u00e9es par des experts et d&rsquo;efforts de coh\u00e9sion renforc\u00e9s afin de s&rsquo;assurer que ces r\u00e9gions contribuent aux objectifs sociaux, \u00e9conomiques et environnementaux plus larges de l&rsquo;Europe et en tirent profit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La deuxi\u00e8me journ\u00e9e de la conf\u00e9rence s&rsquo;est concentr\u00e9e sur <a href=\"https:\/\/www.moving-h2020.eu\/wp-content\/uploads\/2024\/06\/1.MarkRedman_14-06.pdf\">les recommandations politiques de MOVING<\/a> pour lib\u00e9rer le pouvoir des cha\u00eenes de valeur de montagne, en mettant l&rsquo;accent sur la p\u00e9riode de programmation post-2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mark Redman<\/strong>, directeur de Highclere Consulting, a d\u00e9voil\u00e9 la feuille de route politique de MOVING, qui repose sur huit piliers ax\u00e9s sur les besoins : mettre en \u0153uvre une meilleure gouvernance et une meilleure r\u00e9glementation, favoriser la collaboration et la mise en r\u00e9seau, d\u00e9velopper les comp\u00e9tences, les connaissances et l&rsquo;innovation, garantir les moyens de subsistance en montagne, promouvoir la qualit\u00e9 des produits de montagne, soutenir l&rsquo;utilisation des actifs locaux, et se pr\u00e9parer et s&rsquo;adapter au changement.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" style=\"background:linear-gradient(312deg,rgb(255,245,203) 0%,rgb(182,227,212) 50%,rgb(51,167,181) 100%)\">\u00ab\u00a0L&rsquo;AEIDL diffusera dans les prochains jours la feuille de route politique MOVING, qui contient des propositions sp\u00e9cifiques visant \u00e0 modifier les politiques de l&rsquo;UE concernant les zones confront\u00e9es \u00e0 des contraintes g\u00e9ographiques, telles que les zones de montagne, en vue du cadre politique de l&rsquo;UE pour l&rsquo;apr\u00e8s 2027, qui fait d\u00e9j\u00e0 l&rsquo;objet de discussions.\u00a0\u00bb<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les principaux intervenants, tels que <strong>Gustavo Lopez Cutillas<\/strong> du secr\u00e9tariat de la commission REGI du Parlement europ\u00e9en, <strong>Guillaume Corradino<\/strong>, directeur d&rsquo;Euromontana, <strong>Erik Gl\u00f8ersen<\/strong> de Spatial Foresight et <strong>Urszula Budzich Tabor<\/strong> du bureau de soutien du pacte rural, ont soulign\u00e9 que la feuille de route fournit un cadre strat\u00e9gique d\u00e9taill\u00e9 et opportun pour renforcer les cha\u00eenes de valeur en montagne. Ils ont soulign\u00e9 l&rsquo;importance des politiques fond\u00e9es sur des donn\u00e9es probantes et sur le lieu et de la promotion de la collaboration, qui sont cruciales pour le d\u00e9veloppement futur de la politique de l&rsquo;UE et sa mise en \u0153uvre pratique.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-300x200.jpg\" alt=\"\" class=\"wp-image-16388\" srcset=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-300x200.jpg 300w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-1024x683.jpg 1024w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-768x512.jpg 768w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-1536x1024.jpg 1536w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-320x213.jpg 320w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-640x427.jpg 640w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-1280x853.jpg 1280w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477-1920x1280.jpg 1920w, https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6477.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Mar Delgado a conclu la conf\u00e9rence en remerciant tous les participants et en exprimant sa gratitude aux partenaires pour leur travail acharn\u00e9 au cours des quatre derni\u00e8res ann\u00e9es en vue d&rsquo;un avenir meilleur pour les zones de montagne. L&rsquo;\u00e9v\u00e9nement a soulign\u00e9 le r\u00f4le vital que jouent les zones de montagne dans la r\u00e9alisation des objectifs politiques et environnementaux de l&rsquo;Europe \u00e0 l&rsquo;horizon 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos du projet MOVING :<\/strong> Le projet MOVING est un projet H2020 financ\u00e9 par l&rsquo;UE qui se concentre sur le renforcement des capacit\u00e9s et le cod\u00e9veloppement de cadres politiques pour \u00e9tablir des cha\u00eenes de valeur nouvelles ou \u00e0 plus grande \u00e9chelle, contribuant \u00e0 la r\u00e9silience et \u00e0 la durabilit\u00e9 des zones montagneuses en Europe.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img decoding=\"async\" src=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2022\/05\/image.png\" alt=\"This image has an empty alt attribute; its file name is image.png\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>MOVING est financ\u00e9 par le programme de R&amp;I Horizon 2020 de l&rsquo;Union europ\u00e9enne. Le contenu de cet article ne refl\u00e8te pas l&rsquo;opinion officielle de l&rsquo;Union europ\u00e9enne. La responsabilit\u00e9 des informations et des opinions qui y sont exprim\u00e9es incombe enti\u00e8rement \u00e0 l&rsquo;auteur ou aux auteurs.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 13 et 14 juin, la conf\u00e9rence finale du projet MOVING : \u00ab\u00a0Un avenir pour les zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\u00a0\u00bb s&rsquo;est tenue \u00e0 Bruxelles, marquant l&rsquo;aboutissement d&rsquo;un voyage de quatre ans pour le projet. Cet \u00e9v\u00e9nement de haut niveau de deux jours a rassembl\u00e9 plus de 60 participants des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[260,146,64],"tags":[],"class_list":["post-16423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mountain-policy","category-moving","category-sustainability"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La conf\u00e9rence finale de MOVING trace l&#039;avenir des zones de montagne dans les priorit\u00e9s de l&#039;UE apr\u00e8s 2027 - AREPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La conf\u00e9rence finale de MOVING trace l&#039;avenir des zones de montagne dans les priorit\u00e9s de l&#039;UE apr\u00e8s 2027 - AREPO\" \/>\n<meta property=\"og:description\" content=\"Les 13 et 14 juin, la conf\u00e9rence finale du projet MOVING : \u00ab\u00a0Un avenir pour les zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\u00a0\u00bb s&rsquo;est tenue \u00e0 Bruxelles, marquant l&rsquo;aboutissement d&rsquo;un voyage de quatre ans pour le projet. Cet \u00e9v\u00e9nement de haut niveau de deux jours a rassembl\u00e9 plus de 60 participants des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/\" \/>\n<meta property=\"og:site_name\" content=\"AREPO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arepoquality\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T09:38:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T06:54:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesca Alampi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:site\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Alampi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/\"},\"author\":{\"name\":\"Francesca Alampi\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\"},\"headline\":\"La conf\u00e9rence finale de MOVING trace l&rsquo;avenir des zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\",\"datePublished\":\"2024-06-20T09:38:50+00:00\",\"dateModified\":\"2024-07-05T06:54:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/\"},\"wordCount\":1067,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_6558.jpg\",\"articleSection\":[\"Mountain policy\",\"MOVING\",\"Sustainability\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/\",\"name\":\"La conf\u00e9rence finale de MOVING trace l'avenir des zones de montagne dans les priorit\u00e9s de l'UE apr\u00e8s 2027 - AREPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_6558.jpg\",\"datePublished\":\"2024-06-20T09:38:50+00:00\",\"dateModified\":\"2024-07-05T06:54:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_6558.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/img_6558.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2024\\\/06\\\/20\\\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arepoquality.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La conf\u00e9rence finale de MOVING trace l&rsquo;avenir des zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"name\":\"AREPO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arepoquality.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\",\"name\":\"AREPO\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"width\":1113,\"height\":705,\"caption\":\"AREPO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arepoquality\\\/\",\"https:\\\/\\\/x.com\\\/arepoquality_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arepoquality\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\",\"name\":\"Francesca Alampi\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/author\\\/francesca-alampi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La conf\u00e9rence finale de MOVING trace l'avenir des zones de montagne dans les priorit\u00e9s de l'UE apr\u00e8s 2027 - AREPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/","og_locale":"fr_FR","og_type":"article","og_title":"La conf\u00e9rence finale de MOVING trace l'avenir des zones de montagne dans les priorit\u00e9s de l'UE apr\u00e8s 2027 - AREPO","og_description":"Les 13 et 14 juin, la conf\u00e9rence finale du projet MOVING : \u00ab\u00a0Un avenir pour les zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027\u00a0\u00bb s&rsquo;est tenue \u00e0 Bruxelles, marquant l&rsquo;aboutissement d&rsquo;un voyage de quatre ans pour le projet. Cet \u00e9v\u00e9nement de haut niveau de deux jours a rassembl\u00e9 plus de 60 participants des [&hellip;]","og_url":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/","og_site_name":"AREPO","article_publisher":"https:\/\/www.facebook.com\/arepoquality\/","article_published_time":"2024-06-20T09:38:50+00:00","article_modified_time":"2024-07-05T06:54:12+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg","type":"image\/jpeg"}],"author":"Francesca Alampi","twitter_card":"summary_large_image","twitter_creator":"@arepoquality_eu","twitter_site":"@arepoquality_eu","twitter_misc":{"\u00c9crit par":"Francesca Alampi","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#article","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/"},"author":{"name":"Francesca Alampi","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97"},"headline":"La conf\u00e9rence finale de MOVING trace l&rsquo;avenir des zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027","datePublished":"2024-06-20T09:38:50+00:00","dateModified":"2024-07-05T06:54:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/"},"wordCount":1067,"publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"image":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg","articleSection":["Mountain policy","MOVING","Sustainability"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/","url":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/","name":"La conf\u00e9rence finale de MOVING trace l'avenir des zones de montagne dans les priorit\u00e9s de l'UE apr\u00e8s 2027 - AREPO","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#primaryimage"},"image":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg","datePublished":"2024-06-20T09:38:50+00:00","dateModified":"2024-07-05T06:54:12+00:00","breadcrumb":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#primaryimage","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/06\/img_6558.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.arepoquality.eu\/fr\/2024\/06\/20\/la-conference-finale-de-moving-trace-lavenir-des-zones-de-montagne-dans-les-priorites-de-lue-apres-2027\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arepoquality.eu\/"},{"@type":"ListItem","position":2,"name":"La conf\u00e9rence finale de MOVING trace l&rsquo;avenir des zones de montagne dans les priorit\u00e9s de l&rsquo;UE apr\u00e8s 2027"}]},{"@type":"WebSite","@id":"https:\/\/www.arepoquality.eu\/#website","url":"https:\/\/www.arepoquality.eu\/","name":"AREPO","description":"","publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arepoquality.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.arepoquality.eu\/#organization","name":"AREPO","url":"https:\/\/www.arepoquality.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","width":1113,"height":705,"caption":"AREPO"},"image":{"@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arepoquality\/","https:\/\/x.com\/arepoquality_eu","https:\/\/www.linkedin.com\/company\/arepoquality\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97","name":"Francesca Alampi","url":"https:\/\/www.arepoquality.eu\/fr\/author\/francesca-alampi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/16423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/comments?post=16423"}],"version-history":[{"count":2,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/16423\/revisions"}],"predecessor-version":[{"id":16425,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/16423\/revisions\/16425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media\/16396"}],"wp:attachment":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media?parent=16423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/categories?post=16423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/tags?post=16423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}