{"id":18116,"date":"2025-10-27T15:30:47","date_gmt":"2025-10-27T14:30:47","guid":{"rendered":"https:\/\/www.arepoquality.eu\/?p=18116"},"modified":"2025-10-27T15:30:48","modified_gmt":"2025-10-27T14:30:48","slug":"larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne","status":"publish","type":"post","link":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/","title":{"rendered":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De nombreux ministres r\u00e9gionaux et les producteurs d\u2019indications g\u00e9ographiques membres de l\u2019AREPO se sont r\u00e9unies pour leur seconde assembl\u00e9e g\u00e9n\u00e9rale annuelle \u00e0 Barcelone, en Catalogne, R\u00e9gion mondiale de la Gastronomie 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au moment o\u00f9 les institutions europ\u00e9ennes se pr\u00e9parent aux n\u00e9gociations sur la future Politique Agricole Commune (PAC), les membres de l\u2019AREPO ont exprim\u00e9 leurs fortes pr\u00e9occupations face \u00e0 des propositions marqu\u00e9es par une nette r\u00e9duction du budget et une architecture difficile \u00e0 interpr\u00e9ter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019AREPO souhaite engager un dialogue constructif avec les institutions europ\u00e9ennes, afin de comprendre les motivations de ces annonces et de proposer des pistes d\u2019am\u00e9lioration concr\u00e8tes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La volont\u00e9 de la commission europ\u00e9enne avec ce fonds unique et cette architecture qui fait disparaitre les deux piliers de la PAC serait la simplification. Cependant les membres de l\u2019AREPO craignent qu\u2019il s\u2019agisse in fine d\u2019\u00e9conomie et de dilution de moyens, de perte de coh\u00e9sion et de r\u00e9duction du caract\u00e8re commun de la politique agricole.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis les origines de l\u2019Union, l\u2019agriculture a repr\u00e9sent\u00e9 l\u2019un des piliers de la construction europ\u00e9enne et de sa coh\u00e9sion. Une PAC forte est essentielle pour pr\u00e9server ce r\u00f4le et garantir un mod\u00e8le de d\u00e9veloppement \u00e9quilibr\u00e9 et durable pour l\u2019ensemble des territoires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-orange-color\">C\u00e9sar Salda\u00f1a, pr\u00e9sident du coll\u00e8ge des producteurs de l\u2019AREPO<\/mark><\/strong>, a insist\u00e9 <em>\u00ab sur la n\u00e9cessit\u00e9 d\u2019une PAC adapt\u00e9e aux besoins des agriculteurs avec des ressources financi\u00e8res ad\u00e9quates. Les propositions actuellement sur la table n\u2019introduisent aucune mesure r\u00e9pondant aux besoins sp\u00e9cifiques du syst\u00e8me des indications g\u00e9ographiques. Les organisations de producteurs restent exclues des aides directes, sans qu\u2019aucun nouvel instrument de valorisation ou de d\u00e9veloppement des IG ne soit pr\u00e9vu. \u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussi le <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-orange-color\">Pr\u00e9sident de l\u2019AREPO, Alessandro Beduschi<\/mark><\/strong> a rappel\u00e9 que <em>\u00ab la PAC est la garante de la souverainet\u00e9 alimentaire. Nous partageons avec la Commission europ\u00e9enne les priorit\u00e9s du renouvellement des g\u00e9n\u00e9rations en agriculture, de l\u2019adaptation au d\u00e9r\u00e8glement climatique et du d\u00e9veloppement de la recherche. Et concernant l\u2019AREPO, nous sommes pleinement conscientes de la n\u00e9cessit\u00e9 de garantir la durabilit\u00e9 des indications g\u00e9ographiques. Cela ne pourra pas se faire dans la cadre d\u2019un affaiblissement de la PAC , de ses moyens allou\u00e9s et d\u2019une perte de lisibilit\u00e9. En la mati\u00e8re le discours ne peut pas \u00eatre seulement comptable \u00bb.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019AREPO d\u00e9fend une PAC fond\u00e9e sur deux piliers, non par tradition, mais parce qu\u2019ils ont d\u00e9montr\u00e9 leur efficacit\u00e9, et r\u00e9affirme la n\u00e9cessit\u00e9 d\u2019une nouvelle politique agricole commune, plus innovante mais aussi coh\u00e9rente, capable de r\u00e9pondre aux d\u00e9fis actuels de l\u2019agriculture europ\u00e9enne et de pr\u00e9server la souverainet\u00e9 alimentaire de l\u2019Union europ\u00e9enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nombreux ministres r\u00e9gionaux et les producteurs d\u2019indications g\u00e9ographiques membres de l\u2019AREPO se sont r\u00e9unies pour leur seconde assembl\u00e9e g\u00e9n\u00e9rale annuelle \u00e0 Barcelone, en Catalogne, R\u00e9gion mondiale de la Gastronomie 2025. Au moment o\u00f9 les institutions europ\u00e9ennes se pr\u00e9parent aux n\u00e9gociations sur la future Politique Agricole Commune (PAC), les membres de l\u2019AREPO ont exprim\u00e9 leurs [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43,106],"tags":[],"class_list":["post-18116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pac","category-reunions-arepo-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO\" \/>\n<meta property=\"og:description\" content=\"De nombreux ministres r\u00e9gionaux et les producteurs d\u2019indications g\u00e9ographiques membres de l\u2019AREPO se sont r\u00e9unies pour leur seconde assembl\u00e9e g\u00e9n\u00e9rale annuelle \u00e0 Barcelone, en Catalogne, R\u00e9gion mondiale de la Gastronomie 2025. Au moment o\u00f9 les institutions europ\u00e9ennes se pr\u00e9parent aux n\u00e9gociations sur la future Politique Agricole Commune (PAC), les membres de l\u2019AREPO ont exprim\u00e9 leurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/\" \/>\n<meta property=\"og:site_name\" content=\"AREPO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arepoquality\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T14:30:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T14:30:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesca Alampi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:site\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Alampi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/\"},\"author\":{\"name\":\"Francesca Alampi\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\"},\"headline\":\"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne\",\"datePublished\":\"2025-10-27T14:30:47+00:00\",\"dateModified\":\"2025-10-27T14:30:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/arepo-general-assembly-scaled.jpeg\",\"articleSection\":[\"PAC\",\"R\u00e9union AREPO\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/\",\"name\":\"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/arepo-general-assembly-scaled.jpeg\",\"datePublished\":\"2025-10-27T14:30:47+00:00\",\"dateModified\":\"2025-10-27T14:30:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/arepo-general-assembly-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/arepo-general-assembly-scaled.jpeg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/2025\\\/10\\\/27\\\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arepoquality.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"name\":\"AREPO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arepoquality.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\",\"name\":\"AREPO\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"width\":1113,\"height\":705,\"caption\":\"AREPO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arepoquality\\\/\",\"https:\\\/\\\/x.com\\\/arepoquality_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arepoquality\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\",\"name\":\"Francesca Alampi\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/fr\\\/author\\\/francesca-alampi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO","og_description":"De nombreux ministres r\u00e9gionaux et les producteurs d\u2019indications g\u00e9ographiques membres de l\u2019AREPO se sont r\u00e9unies pour leur seconde assembl\u00e9e g\u00e9n\u00e9rale annuelle \u00e0 Barcelone, en Catalogne, R\u00e9gion mondiale de la Gastronomie 2025. Au moment o\u00f9 les institutions europ\u00e9ennes se pr\u00e9parent aux n\u00e9gociations sur la future Politique Agricole Commune (PAC), les membres de l\u2019AREPO ont exprim\u00e9 leurs [&hellip;]","og_url":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/","og_site_name":"AREPO","article_publisher":"https:\/\/www.facebook.com\/arepoquality\/","article_published_time":"2025-10-27T14:30:47+00:00","article_modified_time":"2025-10-27T14:30:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg","type":"image\/jpeg"}],"author":"Francesca Alampi","twitter_card":"summary_large_image","twitter_creator":"@arepoquality_eu","twitter_site":"@arepoquality_eu","twitter_misc":{"\u00c9crit par":"Francesca Alampi","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#article","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/"},"author":{"name":"Francesca Alampi","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97"},"headline":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne","datePublished":"2025-10-27T14:30:47+00:00","dateModified":"2025-10-27T14:30:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/"},"wordCount":510,"publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"image":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg","articleSection":["PAC","R\u00e9union AREPO"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/","url":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/","name":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne - AREPO","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#primaryimage"},"image":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg","datePublished":"2025-10-27T14:30:47+00:00","dateModified":"2025-10-27T14:30:48+00:00","breadcrumb":{"@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#primaryimage","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2025\/10\/arepo-general-assembly-scaled.jpeg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.arepoquality.eu\/fr\/2025\/10\/27\/larepo-demande-une-pac-a-la-hauteur-des-defis-de-lagriculture-europeenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arepoquality.eu\/"},{"@type":"ListItem","position":2,"name":"L\u2019AREPO demande une PAC \u00e0 la hauteur des d\u00e9fis de l\u2019agriculture europ\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/www.arepoquality.eu\/#website","url":"https:\/\/www.arepoquality.eu\/","name":"AREPO","description":"","publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arepoquality.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.arepoquality.eu\/#organization","name":"AREPO","url":"https:\/\/www.arepoquality.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","width":1113,"height":705,"caption":"AREPO"},"image":{"@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arepoquality\/","https:\/\/x.com\/arepoquality_eu","https:\/\/www.linkedin.com\/company\/arepoquality\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97","name":"Francesca Alampi","url":"https:\/\/www.arepoquality.eu\/fr\/author\/francesca-alampi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/18116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/comments?post=18116"}],"version-history":[{"count":1,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/18116\/revisions"}],"predecessor-version":[{"id":18117,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/posts\/18116\/revisions\/18117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media\/18096"}],"wp:attachment":[{"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/media?parent=18116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/categories?post=18116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/fr\/wp-json\/wp\/v2\/tags?post=18116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}