{"id":1944,"date":"2021-06-28T11:42:06","date_gmt":"2021-06-28T09:42:06","guid":{"rendered":"http:\/\/252373706c.url-de-test.ws\/arepo\/?p=1944"},"modified":"2021-06-29T11:45:06","modified_gmt":"2021-06-29T09:45:06","slug":"revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica","status":"publish","type":"post","link":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/","title":{"rendered":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica"},"content":{"rendered":"\n<p>Nel quadro della revisione della politica di qualit\u00e0 dell&#8217;UE, la Commissione europea ha pubblicato una sintesi fattuale dei contributi forniti dalle parti interessate nella&nbsp;<a href=\"https:\/\/ec.europa.eu\/info\/law\/better-regulation\/have-your-say\/initiatives\/12664-Alimenti-e-bevande-Regime-di-indicazioni-geografiche-dellUE-revisione-_it\">consultazione pubblica aperta&nbsp;<\/a>condotta dal 15 gennaio 2021 al 9 aprile 2021.<\/p>\n\n\n\n<p>Un totale di 302 risposte da 31 paesi, di cui 20 Stati membri dell&#8217;UE e 11 paesi non UE, hanno alimentato la discussione sulle sfide che il sistema sta affrontando oggi, nonch\u00e9 sugli obiettivi, l&#8217;approccio politico e l&#8217;impatto della revisione.<\/p>\n\n\n\n<p>Tra le sfide da affrontare con la revisione dei sistemi di qualit\u00e0 dell&#8217;UE, gli intervistati hanno sottolineato l&#8217;importanza di&nbsp;<strong>prevenire le frodi e le contraffazioni,<\/strong>&nbsp;in particolare su Internet, insieme alla necessit\u00e0 di&nbsp;<strong>aumentare la consapevolezza dei consumatori sui loghi IG<\/strong>. Hanno anche valutato come &#8220;pi\u00f9 importante&#8221;&nbsp;<strong>dare ai gruppi di produttori IG maggiori poteri e responsabilit\u00e0<\/strong>, cos\u00ec come&nbsp;<strong>aumentare la sostenibilit\u00e0 dei prodotti IG.<\/strong><\/p>\n\n\n\n<p>Le sfide identificate si riflettono negli obiettivi da perseguire per rafforzare il sistema delle IG dell&#8217;UE:&nbsp;<strong>migliorare la protezione e l&#8217;applicazione delle IG negli Stati membri<\/strong>; stabilire procedure efficienti attraverso&nbsp;<strong>regole chiare e coerenti per i produttori<\/strong>; permettere ai consumatori di fare scelte informate attraverso&nbsp;<strong>informazioni chiare, cio\u00e8 informazioni sul logo e sull&#8217;etichettatura.<\/strong><\/p>\n\n\n\n<p>Ai partecipanti alla consultazione pubblica \u00e8 stato anche chiesto di esprimere la loro preferenza su diverse opzioni politiche per raggiungere questi obiettivi.<\/p>\n\n\n\n<p><strong>Sostenibilit\u00e0 delle indicazioni geografiche dell&#8217;UE<\/strong><\/p>\n\n\n\n<p>Per quanto riguarda la sostenibilit\u00e0, pi\u00f9 della met\u00e0 delle risposte ricevute sono favorevoli a fornire un sostegno finanziario specifico ai produttori di IG che soddisfano un elevato standard di produzione sostenibile. Inoltre, il 77% degli intervistati concorda sul fatto che i produttori di IG non dovrebbero essere obbligati a seguire standard di sostenibilit\u00e0 pi\u00f9 elevati di qualsiasi altro produttore, perch\u00e9 le IG includono intrinsecamente caratteristiche naturali, abilit\u00e0 umane e tradizione della regione.<\/p>\n\n\n\n<p>Considerando la possibilit\u00e0 di aumentare l&#8217;ambizione di questa politica per quanto riguarda le pratiche sostenibili economiche, sociali e ambientali, l<strong>e risposte indicano un impatto positivo o molto positivo<\/strong>, in particolare sulla conservazione della biodiversit\u00e0, degli habitat, dei paesaggi, delle variet\u00e0 e delle razze vegetali locali (86%), sui modelli di produzione rispettosi dell&#8217;ambiente (82%) e sul rafforzamento della coesione economica, sociale e territoriale delle zone rurali (77%). Si ritiene che la sostenibilit\u00e0 abbia anche un effetto positivo sull&#8217;aumento della consapevolezza dei consumatori sui sistemi di qualit\u00e0&nbsp;(74%).<\/p>\n\n\n\n<p>D&#8217;altra parte, la maggior parte degli stakeholder sottolinea l&#8217;impatto negativo che misure aggiuntive di sostenibilit\u00e0 possono avere sui costi per i produttori di IG (48%) e sugli oneri per la pubblica amministrazione (29%).<\/p>\n\n\n\n<p><strong>Revisione del sistema STG<\/strong><\/p>\n\n\n\n<p>A causa delle difficolt\u00e0 del sistema delle Specialit\u00e0 Tradizionali Garantite (STG) a decollare e a farsi riconoscere da produttori e consumatori, una sezione del questionario online \u00e8 stata dedicata a fare il punto sulle possibili opzioni di revisione del sistema STG. La maggioranza degli intervistati (59%)&nbsp;<strong>si \u00e8 opposta all&#8217;idea che non sia necessario un regime STG a livello UE<\/strong>, concordando sul fatto che i nomi dei prodotti agricoli tradizionali dovrebbero essere rigorosamente protetti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel quadro della revisione della politica di qualit\u00e0 dell&#8217;UE, la Commissione europea ha pubblicato una sintesi fattuale dei contributi forniti dalle parti interessate nella&nbsp;consultazione pubblica aperta&nbsp;condotta dal 15 gennaio 2021 al 9 aprile 2021. Un totale di 302 risposte da 31 paesi, di cui 20 Stati membri dell&#8217;UE e 11 paesi non UE, hanno alimentato [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40,125,131],"tags":[],"class_list":["post-1944","post","type-post","status-publish","format-standard","hentry","category-politica-di-qualita","category-sistemi-di-qualita-it","category-sostenibilita-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO\" \/>\n<meta property=\"og:description\" content=\"Nel quadro della revisione della politica di qualit\u00e0 dell&#8217;UE, la Commissione europea ha pubblicato una sintesi fattuale dei contributi forniti dalle parti interessate nella&nbsp;consultazione pubblica aperta&nbsp;condotta dal 15 gennaio 2021 al 9 aprile 2021. Un totale di 302 risposte da 31 paesi, di cui 20 Stati membri dell&#8217;UE e 11 paesi non UE, hanno alimentato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/\" \/>\n<meta property=\"og:site_name\" content=\"AREPO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arepoquality\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T09:42:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-29T09:45:06+00:00\" \/>\n<meta name=\"author\" content=\"Francesca Alampi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:site\" content=\"@arepoquality_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Alampi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/\"},\"author\":{\"name\":\"Francesca Alampi\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\"},\"headline\":\"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica\",\"datePublished\":\"2021-06-28T09:42:06+00:00\",\"dateModified\":\"2021-06-29T09:45:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"articleSection\":[\"Politica di qualit\u00e0\",\"Sistemi di qualit\u00e0\",\"Sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/\",\"name\":\"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\"},\"datePublished\":\"2021-06-28T09:42:06+00:00\",\"dateModified\":\"2021-06-29T09:45:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/2021\\\/06\\\/28\\\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arepoquality.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"name\":\"AREPO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arepoquality.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#organization\",\"name\":\"AREPO\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arepoquality.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/arepo.jpg\",\"width\":1113,\"height\":705,\"caption\":\"AREPO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arepoquality\\\/\",\"https:\\\/\\\/x.com\\\/arepoquality_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arepoquality\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arepoquality.eu\\\/#\\\/schema\\\/person\\\/15f7c6b22cbe9706c69d5201712ded97\",\"name\":\"Francesca Alampi\",\"url\":\"https:\\\/\\\/www.arepoquality.eu\\\/it\\\/author\\\/francesca-alampi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/","og_locale":"it_IT","og_type":"article","og_title":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO","og_description":"Nel quadro della revisione della politica di qualit\u00e0 dell&#8217;UE, la Commissione europea ha pubblicato una sintesi fattuale dei contributi forniti dalle parti interessate nella&nbsp;consultazione pubblica aperta&nbsp;condotta dal 15 gennaio 2021 al 9 aprile 2021. Un totale di 302 risposte da 31 paesi, di cui 20 Stati membri dell&#8217;UE e 11 paesi non UE, hanno alimentato [&hellip;]","og_url":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/","og_site_name":"AREPO","article_publisher":"https:\/\/www.facebook.com\/arepoquality\/","article_published_time":"2021-06-28T09:42:06+00:00","article_modified_time":"2021-06-29T09:45:06+00:00","author":"Francesca Alampi","twitter_card":"summary_large_image","twitter_creator":"@arepoquality_eu","twitter_site":"@arepoquality_eu","twitter_misc":{"Scritto da":"Francesca Alampi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/#article","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/"},"author":{"name":"Francesca Alampi","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97"},"headline":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica","datePublished":"2021-06-28T09:42:06+00:00","dateModified":"2021-06-29T09:45:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"articleSection":["Politica di qualit\u00e0","Sistemi di qualit\u00e0","Sostenibilit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/","url":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/","name":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica - AREPO","isPartOf":{"@id":"https:\/\/www.arepoquality.eu\/#website"},"datePublished":"2021-06-28T09:42:06+00:00","dateModified":"2021-06-29T09:45:06+00:00","breadcrumb":{"@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arepoquality.eu\/it\/2021\/06\/28\/revisione-del-sistema-ig-ue-la-ce-pubblica-una-sintesi-dei-contributi-alla-consultazione-pubblica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arepoquality.eu\/"},{"@type":"ListItem","position":2,"name":"Revisione del sistema IG UE: la CE pubblica una sintesi dei contributi alla consultazione pubblica"}]},{"@type":"WebSite","@id":"https:\/\/www.arepoquality.eu\/#website","url":"https:\/\/www.arepoquality.eu\/","name":"AREPO","description":"","publisher":{"@id":"https:\/\/www.arepoquality.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arepoquality.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.arepoquality.eu\/#organization","name":"AREPO","url":"https:\/\/www.arepoquality.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","contentUrl":"https:\/\/www.arepoquality.eu\/wp-content\/uploads\/2024\/05\/arepo.jpg","width":1113,"height":705,"caption":"AREPO"},"image":{"@id":"https:\/\/www.arepoquality.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arepoquality\/","https:\/\/x.com\/arepoquality_eu","https:\/\/www.linkedin.com\/company\/arepoquality\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.arepoquality.eu\/#\/schema\/person\/15f7c6b22cbe9706c69d5201712ded97","name":"Francesca Alampi","url":"https:\/\/www.arepoquality.eu\/it\/author\/francesca-alampi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/posts\/1944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/comments?post=1944"}],"version-history":[{"count":2,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/posts\/1944\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/posts\/1944\/revisions\/1946"}],"wp:attachment":[{"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/media?parent=1944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/categories?post=1944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arepoquality.eu\/it\/wp-json\/wp\/v2\/tags?post=1944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}